{"id":831,"date":"2024-07-19T10:00:03","date_gmt":"2024-07-19T13:00:03","guid":{"rendered":"https:\/\/jornalvalenews.com.br\/?p=831"},"modified":"2024-07-19T11:02:33","modified_gmt":"2024-07-19T14:02:33","slug":"baltazar-luiz-lidera-disputa-eleitoral-com-482-das-intencoes-de-voto-em-ipiranga-de-goias-aponta-pesquisa","status":"publish","type":"post","link":"https:\/\/jornalvalenews.com.br\/index.php\/2024\/07\/19\/baltazar-luiz-lidera-disputa-eleitoral-com-482-das-intencoes-de-voto-em-ipiranga-de-goias-aponta-pesquisa\/","title":{"rendered":"Baltazar Luiz lidera disputa eleitoral com 48,2% das inten\u00e7\u00f5es de voto em Ipiranga de Goi\u00e1s, aponta pesquisa"},"content":{"rendered":"<div class=\"col-md-12 espc-height txt-tam12\">\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/api.whatsapp.com\/send?phone=5562994225999&amp;text=Ol%C3%A1,%20gostaria%20de%20saber%20mais%20sobre%20os%20an%C3%BAncios%20no%20Jornal%20Vale%20News.%20\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/03\/arte-2024-anuncio-Copia-716x1024.png\" alt=\"\" width=\"400\" height=\"572\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Em novo levantamento realizado pela Direct Pesquisas, o pr\u00e9-candidato a prefeito de Ipiranga de Goi\u00e1s <strong>Baltazar Luiz<\/strong> (Uni\u00e3o Brasil) aparece com 48,2% das inten\u00e7\u00f5es de voto na pesquisa estimulada.<\/p>\n<p>Mais uma rodada de pesquisa registrada sobre as elei\u00e7\u00f5es na cidade de Ipiranga de Goi\u00e1s, que agora conta com os nomes dos dois principais pr\u00e9-candidatos j\u00e1 praticamente definidos, indica que, o agropecuarista, Baltazar Luiz (Uni\u00e3o Brasil) lidera a corrida eleitoral em todos os cen\u00e1rios pesquisados. Baltazar lidera uma frente de oposi\u00e7\u00e3o contra Z\u00e9 Mauro, da base do prefeito Alex G\u00e1s, que tenta emplacar seu sucessor.<\/p>\n<p>De acordo com a Direct Pesquisas, Baltazar Luiz aparece com 48,2% das inten\u00e7\u00f5es de voto na pesquisa estimulada contra 35,8% do pr\u00e9-candidato Z\u00e9 Mauro (PL). De acordo com cientistas pol\u00edticos, o cen\u00e1rio estimulado \u00e9 o que mais reflete a inten\u00e7\u00e3o de votos em uma pesquisa, isso porque, \u00e9 apresentado ao entrevistado apenas os dois nomes dos principais candidatos na disputa. Os entrevistados que anulariam os votos nesse cen\u00e1rio somaram 5,1% e os que n\u00e3o sabem foi de 10,9%.<\/p>\n<p>J\u00e1 no cen\u00e1rio espont\u00e2neo, aquele em que o cidad\u00e3o indica o candidato de sua prefer\u00eancia sem olhar para uma cartela com nomes, o pr\u00e9-candidato Baltazar Luiz lidera a corrida sucess\u00f3ria com 38,7% das inten\u00e7\u00f5es de votos. Z\u00e9 Mauro \u00e9 o segundo colocado com 34,6%. A vereadora Meire aparece com 2,7% e com 1,1% das inten\u00e7\u00f5es de votos aparecem Adriana, Z\u00e9 Careca e Juvenil. Os que entrevistados que anulariam os votos somam 2,7% e os que n\u00e3o sabem somam 16,5%.<\/p>\n<p><b>Metodologia<\/b><\/p>\n<p>A Direct Pesquisas fez o levantamento em Ipiranga de Goi\u00e1s entrevistando 260 eleitores no dia nove de julho. A margem de erro \u00e9 de 5,8% pontos percentuais para mais ou para menos e o n\u00edvel de confian\u00e7a \u00e9 de 95%. O n\u00famero de registro no Tribunal Superior Eleitoral (TSE) \u00e9: GO-07874\/2024.<\/p>\n<p><strong>Leia tamb\u00e9m<\/strong><\/p>\n<\/div>\n<div class=\"col-md-12\">\n<div class=\"linha-rp\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"4uNJhcFPUG\"><p><a href=\"https:\/\/jornalvalenews.com.br\/index.php\/2024\/07\/10\/pre-candidato-a-prefeito-em-ipiranga-de-goias-baltazar-luiz-ganha-apoio-de-irma-lucia-atual-vice-prefeita\/\">Pr\u00e9-candidato a prefeito em Ipiranga de Goi\u00e1s, Baltazar Luiz, ganha apoio de Irm\u00e3 L\u00facia, atual vice-prefeita<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u201cPr\u00e9-candidato a prefeito em Ipiranga de Goi\u00e1s, Baltazar Luiz, ganha apoio de Irm\u00e3 L\u00facia, atual vice-prefeita\u201d \u2014 A not\u00edcia que vale mais\" src=\"https:\/\/jornalvalenews.com.br\/index.php\/2024\/07\/10\/pre-candidato-a-prefeito-em-ipiranga-de-goias-baltazar-luiz-ganha-apoio-de-irma-lucia-atual-vice-prefeita\/embed\/#?secret=irsvtDbnog#?secret=4uNJhcFPUG\" data-secret=\"4uNJhcFPUG\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Em novo levantamento realizado pela Direct Pesquisas, o pr\u00e9-candidato a prefeito de Ipiranga de Goi\u00e1s Baltazar Luiz (Uni\u00e3o Brasil) aparece com 48,2% das inten\u00e7\u00f5es de voto na pesquisa estimulada. Mais uma rodada de pesquisa registrada sobre as elei\u00e7\u00f5es na cidade de Ipiranga de Goi\u00e1s, que agora conta com os nomes dos dois principais [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":832,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[8,5,9],"tags":[144,139,138,174],"class_list":["post-831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-goias","category-politica","category-vale-do-sao-patricio","tag-baltazar-luiz","tag-eleicoes-municipais","tag-ipiranga-de-goias","tag-uniao-brasil"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/07\/21a-Semana-29.png","_links":{"self":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=831"}],"version-history":[{"count":2,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/831\/revisions"}],"predecessor-version":[{"id":834,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/831\/revisions\/834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/media\/832"}],"wp:attachment":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}