{"id":5422,"date":"2026-03-25T19:31:51","date_gmt":"2026-03-25T22:31:51","guid":{"rendered":"https:\/\/jornalvalenews.com.br\/?p=5422"},"modified":"2026-03-25T20:16:50","modified_gmt":"2026-03-25T23:16:50","slug":"policia-civil-conclui-inquerito-e-indicia-professor-por-estupro-de-vulneravel-em-uruana","status":"publish","type":"post","link":"https:\/\/jornalvalenews.com.br\/index.php\/2026\/03\/25\/policia-civil-conclui-inquerito-e-indicia-professor-por-estupro-de-vulneravel-em-uruana\/","title":{"rendered":"Pol\u00edcia Civil conclui inqu\u00e9rito e indicia professor por estupro de vulner\u00e1vel em Uruana"},"content":{"rendered":"<div class=\"relative basis-auto flex-col -mb-(--composer-overlap-px) pb-(--composer-overlap-px) [--composer-overlap-px:28px] grow flex\">\n<div class=\"flex flex-col text-sm pb-25\">\n<section class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-69c2cd02-22f0-83e9-b175-0d43da5486c2-3\" data-testid=\"conversation-turn-92\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"45463920-f19f-4b56-bcc1-b195e81114ed\" data-message-model-slug=\"gpt-5-3\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"streaming-animation markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\">\n<p data-start=\"339\" data-end=\"525\"><a href=\"https:\/\/api.whatsapp.com\/send?phone=5562998212725&amp;text=Ol%C3%A1,%20gostaria%20de%20falar%20com%20a%20secret%C3%A1ria%20do%20Dr.%20Paulo%20e%20Dra.%20Caroline\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone\" src=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/08\/novo-gif-dr.-paulo.gif\" alt=\"\" width=\"800\" height=\"666\" \/><\/a><\/p>\n<p data-start=\"339\" data-end=\"525\">A Pol\u00edcia Civil do Estado de Goi\u00e1s concluiu o inqu\u00e9rito policial que apura um caso de <strong data-start=\"425\" data-end=\"524\">estupro de vulner\u00e1vel ocorrido no interior de uma institui\u00e7\u00e3o de ensino, no munic\u00edpio de Uruana<\/strong>.<\/p>\n<p data-start=\"527\" data-end=\"743\">De acordo com o delegado <strong data-start=\"552\" data-end=\"569\">Douglas Costa<\/strong>, respons\u00e1vel pelas investiga\u00e7\u00f5es, o caso envolve um professor da rede p\u00fablica suspeito de manter atos de natureza sexual com <strong data-start=\"695\" data-end=\"742\">uma adolescente com defici\u00eancia intelectual<\/strong>.<\/p>\n<p data-start=\"745\" data-end=\"1111\">Durante a apura\u00e7\u00e3o, foram realizadas dilig\u00eancias como <strong data-start=\"799\" data-end=\"886\">oitivas de testemunhas, an\u00e1lise de relat\u00f3rio do Conselho Tutelar e exames periciais<\/strong>. Os elementos reunidos indicam a materialidade dos fatos, especialmente por meio de laudos t\u00e9cnicos, incluindo <strong data-start=\"998\" data-end=\"1110\">avalia\u00e7\u00e3o psiqui\u00e1trica forense que aponta comprometimento relevante da capacidade de discernimento da v\u00edtima<\/strong>.<\/p>\n<p data-start=\"1113\" data-end=\"1278\">Segundo a investiga\u00e7\u00e3o, a condi\u00e7\u00e3o da adolescente a enquadra legalmente como <strong data-start=\"1190\" data-end=\"1277\">pessoa em situa\u00e7\u00e3o de vulnerabilidade, incapaz de consentir com atos dessa natureza<\/strong>.<\/p>\n<p data-start=\"1280\" data-end=\"1429\">Ainda conforme apurado, <strong data-start=\"1304\" data-end=\"1428\">depoimentos e mensagens analisadas indicam que os fatos teriam ocorrido mais de uma vez, dentro da institui\u00e7\u00e3o de ensino<\/strong>.<\/p>\n<p data-start=\"1431\" data-end=\"1649\">O investigado negou as acusa\u00e7\u00f5es durante o interrogat\u00f3rio. No entanto, de acordo com a Pol\u00edcia Civil, o conjunto de elementos foi considerado suficiente para o <strong data-start=\"1591\" data-end=\"1648\">indiciamento com base no artigo 217-A do C\u00f3digo Penal<\/strong>.<\/p>\n<p data-start=\"1651\" data-end=\"1783\">O inqu\u00e9rito foi conclu\u00eddo e encaminhado ao Poder Judici\u00e1rio, com remessa ao Minist\u00e9rio P\u00fablico para as provid\u00eancias legais cab\u00edveis.<\/p>\n<p data-start=\"1785\" data-end=\"2002\">O delegado Douglas Costa destacou que a Pol\u00edcia Civil mant\u00e9m o compromisso com a <strong data-start=\"1866\" data-end=\"2001\">apura\u00e7\u00e3o rigorosa de crimes dessa natureza, especialmente quando envolvem v\u00edtimas em condi\u00e7\u00e3o de vulnerabilidade e ambiente escolar<\/strong>.<\/p>\n<h3 data-start=\"1143\" data-end=\"1245\">Veja o v\u00eddeo:\u00a0<a href=\"https:\/\/www.instagram.com\/jornalvalenews\/reel\/DWU0nA-kZK8\/\" target=\"_blank\" rel=\"noopener\">clique aqui!<\/a><\/h3>\n<h3 data-start=\"2294\" data-end=\"2377\"><strong>Siga o Instagram do @jornalvalenews e fique por dentro das principais not\u00edcias.\u00a0<\/strong><\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Pol\u00edcia Civil do Estado de Goi\u00e1s concluiu o inqu\u00e9rito policial que apura um caso de estupro de vulner\u00e1vel ocorrido no interior de uma institui\u00e7\u00e3o de ensino, no munic\u00edpio de Uruana. De acordo com o delegado Douglas Costa, respons\u00e1vel pelas investiga\u00e7\u00f5es, o caso envolve um professor da rede p\u00fablica suspeito de manter atos de natureza [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[7,8,9],"tags":[906,908,907,29],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2026\/03\/Inserir-um-titulo-2026-03-25T193111.486.png","_links":{"self":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5422"}],"collection":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5422"}],"version-history":[{"count":2,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5422\/revisions"}],"predecessor-version":[{"id":5428,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5422\/revisions\/5428"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/media\/5423"}],"wp:attachment":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}