{"id":411,"date":"2024-04-23T19:17:44","date_gmt":"2024-04-23T22:17:44","guid":{"rendered":"https:\/\/jornalvalenews.com.br\/?p=411"},"modified":"2024-04-23T19:17:44","modified_gmt":"2024-04-23T22:17:44","slug":"prefeitura-de-rialma-juntamente-com-a-equipe-do-governo-do-estado-realiza-a-entrega-dos-cartoes-do-programa-maes-de-goias","status":"publish","type":"post","link":"https:\/\/jornalvalenews.com.br\/index.php\/2024\/04\/23\/prefeitura-de-rialma-juntamente-com-a-equipe-do-governo-do-estado-realiza-a-entrega-dos-cartoes-do-programa-maes-de-goias\/","title":{"rendered":"Prefeitura de Rialma, juntamente com a equipe do Governo do Estado, realiza a entrega dos cart\u00f5es do programa &#8220;M\u00e3es de Goi\u00e1s&#8221;"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.rialma.go.gov.br\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/03\/logo-prefeitura-de-rialma.png\" alt=\"\" width=\"350\" height=\"300\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Nesta ter\u00e7a-feira, 23 de abril, a Prefeitura de Rialma, por meio da Secretaria Municipal de Assist\u00eancia Social, recebeu a equipe do Governo do Estado de Goi\u00e1s para realizar a entrega dos cart\u00f5es do programa &#8220;M\u00e3es de Goi\u00e1s&#8221; e tamb\u00e9m dos cart\u00f5es do programa social &#8220;Dignidade&#8221;.<\/p>\n<p>A Prefeitura de Rialma se manifestou agradecendo imensamente ao governador Ronaldo Caiado e \u00e0 primeira-dama do estado, Gracinha Caiado, pelo benef\u00edcio. O Poder Executivo Municipal destacou que os programas al\u00e9m de ajudarem as fam\u00edlias que precisam de complementa\u00e7\u00e3o de renda tamb\u00e9m auxiliam a fomentar o com\u00e9rcio local.<\/p>\n<p>A prefeitura finalizou dizendo que esta \u00e9 &#8220;uma solu\u00e7\u00e3o plural para dar mais dignidade \u00e0 comunidade&#8221;. <em>Veja fotos do evento clicando na galeira abaixo:<\/em><\/p>\n<style type=\"text\/css\">\n\t#foogallery-gallery-424 .fg-image {\n        width: 150px;\n    }\n<\/style>\n\t\t\t\t<div class=\"foogallery foogallery-container foogallery-default foogallery-lightbox-foogallery fg-gutter-10 fg-center fg-default fg-light fg-border-thin fg-shadow-outline fg-loading-default fg-loaded-fade-in fg-caption-hover fg-hover-fade fg-hover-zoom fg-ready\" id=\"foogallery-gallery-424\" data-foogallery=\"{&quot;item&quot;:{&quot;showCaptionTitle&quot;:true,&quot;showCaptionDescription&quot;:true},&quot;lazy&quot;:true}\" data-foogallery-lightbox=\"{&quot;thumbs&quot;:&quot;bottom&quot;,&quot;thumbsCaptions&quot;:false,&quot;thumbsBestFit&quot;:false,&quot;thumbsSmall&quot;:false,&quot;thumbsCaptionsAlign&quot;:&quot;default&quot;,&quot;info&quot;:&quot;bottom&quot;,&quot;infoVisible&quot;:true,&quot;infoOverlay&quot;:true,&quot;infoAlign&quot;:&quot;default&quot;,&quot;transition&quot;:&quot;fade&quot;,&quot;hoverButtons&quot;:false,&quot;fitMedia&quot;:false,&quot;noScrollbars&quot;:true,&quot;preserveButtonSpace&quot;:true,&quot;buttons&quot;:{&quot;fullscreen&quot;:true,&quot;info&quot;:true,&quot;thumbs&quot;:false},&quot;video&quot;:{&quot;autoPlay&quot;:true}}\" >\n\t<div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.30-2.jpeg\" data-attachment-id=\"419\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_30-2\/1070277307.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.29.jpeg\" data-attachment-id=\"417\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_29\/909600022.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.30-1.jpeg\" data-attachment-id=\"418\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_30-1\/424293027.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.28-1.jpeg\" data-attachment-id=\"414\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_28-1\/3162327573.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.27.jpeg\" data-attachment-id=\"413\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_27\/3250869829.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.30.jpeg\" data-attachment-id=\"420\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_30\/1641467494.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.31.jpeg\" data-attachment-id=\"421\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_31\/264102277.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.28-2.jpeg\" data-attachment-id=\"415\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_28-2\/2600229389.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.34.jpeg\" data-attachment-id=\"422\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_34\/3457869866.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.35.jpeg\" data-attachment-id=\"423\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_35\/2691811273.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.28.jpeg\" data-attachment-id=\"416\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_28\/1482443509.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.25.jpeg\" data-attachment-id=\"412\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/cache\/2024\/04\/WhatsApp-Image-2024-04-23-at-17_24_25\/2518828387.jpeg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22150%22%20height%3D%22150%22%20viewBox%3D%220%200%20150%20150%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Nesta ter\u00e7a-feira, 23 de abril, a Prefeitura de Rialma, por meio da Secretaria Municipal de Assist\u00eancia Social, recebeu a equipe do Governo do Estado de Goi\u00e1s para realizar a entrega dos cart\u00f5es do programa &#8220;M\u00e3es de Goi\u00e1s&#8221; e tamb\u00e9m dos cart\u00f5es do programa social &#8220;Dignidade&#8221;. A Prefeitura de Rialma se manifestou agradecendo imensamente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":412,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[8,5,12],"tags":[],"class_list":["post-411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-goias","category-politica","category-rialma"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/WhatsApp-Image-2024-04-23-at-17.24.25.jpeg","_links":{"self":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=411"}],"version-history":[{"count":2,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/411\/revisions"}],"predecessor-version":[{"id":431,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/411\/revisions\/431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/media\/412"}],"wp:attachment":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}