{"id":366,"date":"2024-04-12T18:07:24","date_gmt":"2024-04-12T21:07:24","guid":{"rendered":"https:\/\/jornalvalenews.com.br\/?p=366"},"modified":"2024-04-12T18:07:24","modified_gmt":"2024-04-12T21:07:24","slug":"prefeitura-de-ceres-comunica-que-acontecera-neste-sabado-13-o-dia-d-de-vacinacao-contra-a-influenza-saiba-mais","status":"publish","type":"post","link":"https:\/\/jornalvalenews.com.br\/index.php\/2024\/04\/12\/prefeitura-de-ceres-comunica-que-acontecera-neste-sabado-13-o-dia-d-de-vacinacao-contra-a-influenza-saiba-mais\/","title":{"rendered":"Prefeitura de Ceres comunica que acontecer\u00e1 neste s\u00e1bado (13) o &#8220;Dia D de Vacina\u00e7\u00e3o Contra a Influenza&#8221;: saiba mais"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/ceres.go.gov.br\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/03\/banner-prefeitura-de-ceres.png\" alt=\"\" width=\"350\" height=\"280\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Neste s\u00e1bado, 13 de abril, acontecer\u00e1 em todas as unidades b\u00e1sicas de sa\u00fade de Ceres o &#8220;Dia D de Vacina\u00e7\u00e3o Contra a Influenza&#8221;.<\/p>\n<p>A vacina\u00e7\u00e3o acontecer\u00e1 das 08h \u00e0s 16h. A Secretaria Municipal de Sa\u00fade (SMS) de Ceres refor\u00e7a que esta \u00e9 uma oportunidade \u00fanica de garantir a prote\u00e7\u00e3o contra a gripe e fortalecer a imunidade.<\/p>\n<p>O imunizante utilizado \u00e9 trivalente, oferecendo prote\u00e7\u00e3o contra tr\u00eas tipos de cepas de v\u00edrus, incluindo os principais em circula\u00e7\u00e3o no Brasil. A vacina\u00e7\u00e3o estar\u00e1 dispon\u00edvel para toda os grupos priorit\u00e1rios. N\u00e3o deixe de se proteger contra a gripe. <strong><em>Confira abaixo as informa\u00e7\u00f5es:<\/em><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-369 aligncenter\" src=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/sjansjas-300x300.jpg\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/sjansjas-300x300.jpg 300w, https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/sjansjas-1024x1024.jpg 1024w, https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/sjansjas-150x150.jpg 150w, https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/sjansjas-768x768.jpg 768w, https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/sjansjas.jpg 1300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-370 aligncenter\" src=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/ksamksmlams-300x300.jpg\" alt=\"\" width=\"700\" height=\"700\" srcset=\"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/ksamksmlams-300x300.jpg 300w, https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/ksamksmlams-1024x1024.jpg 1024w, https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/ksamksmlams-150x150.jpg 150w, https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/ksamksmlams-768x768.jpg 768w, https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/ksamksmlams.jpg 1300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Neste s\u00e1bado, 13 de abril, acontecer\u00e1 em todas as unidades b\u00e1sicas de sa\u00fade de Ceres o &#8220;Dia D de Vacina\u00e7\u00e3o Contra a Influenza&#8221;. A vacina\u00e7\u00e3o acontecer\u00e1 das 08h \u00e0s 16h. A Secretaria Municipal de Sa\u00fade (SMS) de Ceres refor\u00e7a que esta \u00e9 uma oportunidade \u00fanica de garantir a prote\u00e7\u00e3o contra a gripe e [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[11,8,5,46],"tags":[],"class_list":["post-366","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ceres","category-goias","category-politica","category-saude"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2024\/04\/Design-sem-nome-19.png","_links":{"self":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/366","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=366"}],"version-history":[{"count":2,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/366\/revisions"}],"predecessor-version":[{"id":372,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/366\/revisions\/372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/media\/371"}],"wp:attachment":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=366"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}