{"id":3628,"date":"2025-05-31T14:43:14","date_gmt":"2025-05-31T17:43:14","guid":{"rendered":"https:\/\/jornalvalenews.com.br\/?p=3628"},"modified":"2025-06-05T14:44:40","modified_gmt":"2025-06-05T17:44:40","slug":"secretaria-de-saude-de-ceres-informa-vacinacao-contra-o-hpv-ja-comecou-no-municipio","status":"publish","type":"post","link":"https:\/\/jornalvalenews.com.br\/index.php\/2025\/05\/31\/secretaria-de-saude-de-ceres-informa-vacinacao-contra-o-hpv-ja-comecou-no-municipio\/","title":{"rendered":"Secretaria de Sa\u00fade de Ceres informa: vacina\u00e7\u00e3o contra o HPV j\u00e1 come\u00e7ou no munic\u00edpio"},"content":{"rendered":"<p data-start=\"220\" data-end=\"560\">A Prefeitura de Ceres, por meio da Secretaria Municipal de Sa\u00fade, iniciou a vacina\u00e7\u00e3o contra o HPV para uma nova faixa et\u00e1ria. Agora, jovens entre 15 e 19 anos tamb\u00e9m podem receber a dose da vacina, considerada a forma mais eficaz de prevenir diversos tipos de c\u00e2ncer relacionados ao v\u00edrus, como os de colo do \u00fatero, garganta, p\u00eanis e \u00e2nus.<\/p>\n<p data-start=\"562\" data-end=\"804\">A amplia\u00e7\u00e3o do p\u00fablico-alvo segue orienta\u00e7\u00e3o do Minist\u00e9rio da Sa\u00fade e tem como objetivo aumentar a cobertura vacinal entre adolescentes e jovens adultos. Para garantir a imuniza\u00e7\u00e3o, basta procurar a Unidade B\u00e1sica de Sa\u00fade (UBS) mais pr\u00f3xima.<\/p>\n<p data-start=\"806\" data-end=\"1041\">A vacina est\u00e1 dispon\u00edvel gratuitamente em todas as unidades de sa\u00fade de Ceres. A Secretaria Municipal de Sa\u00fade refor\u00e7a a import\u00e2ncia da preven\u00e7\u00e3o como caminho para uma vida saud\u00e1vel e convoca os jovens a aproveitarem essa oportunidade.<\/p>\n<p data-start=\"1043\" data-end=\"1112\">A campanha j\u00e1 est\u00e1 em andamento e segue enquanto durarem os estoques.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Ceres, por meio da Secretaria Municipal de Sa\u00fade, iniciou a vacina\u00e7\u00e3o contra o HPV para uma nova faixa et\u00e1ria. Agora, jovens entre 15 e 19 anos tamb\u00e9m podem receber a dose da vacina, considerada a forma mais eficaz de prevenir diversos tipos de c\u00e2ncer relacionados ao v\u00edrus, como os de colo do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false}}},"categories":[11,8,46,9],"tags":[],"class_list":["post-3628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ceres","category-goias","category-saude","category-vale-do-sao-patricio"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/jornalvalenews.com.br\/wp-content\/uploads\/2025\/06\/2023-06-13-vacina-hpv-9-valente.webp","_links":{"self":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3628"}],"version-history":[{"count":1,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3628\/revisions"}],"predecessor-version":[{"id":3630,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3628\/revisions\/3630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/media\/3629"}],"wp:attachment":[{"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalvalenews.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}